{"id":48840,"date":"2022-01-24T22:19:55","date_gmt":"2022-01-24T21:19:55","guid":{"rendered":"https:\/\/www.spring-reiter.de\/?p=48840"},"modified":"2022-01-24T22:20:01","modified_gmt":"2022-01-24T21:20:01","slug":"janne-meyers-goja-wird-lehrpferd-in-spanien","status":"publish","type":"post","link":"https:\/\/www.spring-reiter.de\/en\/index.php\/2022\/01\/24\/janne-meyers-goja-wird-lehrpferd-in-spanien\/","title":{"rendered":"Janne Meyers Goja wird Lehrpferd in Spanien!"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Das war keine leichte Entscheidung f\u00fcr die ehemalige Mannschafts- Welt- und -Europameisterin Janne Friederike Meyer-Zimmermann: Gestern hat ihr ehemaliges Top-Pferd Goja (v. Wandor vd Mispelaere) den Hof Waterkant in Richtung Spanien verlassen. Der 16j\u00e4hrige Wallach wird k\u00fcnftig als Lehrmeister f\u00fcr einen Children-Reiter seinen Hafer verdienen. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Janne Friederike Meyer-Zimmermann hat ihre Gef\u00fchle und gemeinsamen Erinnerungen so zusammen gefa\u00dft: <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Gestern musste ich mich von meinem langj\u00e4hrigen Freund und Erfolgspferd Goja verabschieden. Das war f\u00fcr uns alle ein schwieriger Tag und es sind viele Tr\u00e4nen geflossen! Goja ist ein Ausnahmepferd!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seine Art zu springen ist alles andere als klassisch, aber er ist ein Pferd das Springen liebt, auf den ich mich immer zu 100 Prozent verlassen konnte und der mit mir \u00fcber die h\u00f6chsten Parcours der Welt geflogen ist, als w\u00e4ren sie kleine Cavalettis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Er kam mit 7 Jahren zu mir in den Stall und gemeinsam haben wir es nach der Verabschiedung von meinem Cellagon Lambrasco zur\u00fcck in den A-Kader geschafft.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir sind zusammen als Freunde um die Welt gereist &#8211; Gemeinsam waren wir u.a. in den 5* Gro\u00dfen Preisen von Aachen, Hamburg, Stuttgart, Doha, St. Gallen, Wien, Br\u00fcssel, Barcelona, Villach, Mannheim,\u2026 platziert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir beide gewannen mit dem Team Germany das Nationenpreis-Finale f\u00fcr Deutschland und waren Doppelnull und siegreich in vielen Nationenpreisen, z.B. in Hickstead, Falsterbo und Sopot.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zusammen haben wir die Riders Tour gewonnen und konnten in vielen gro\u00dfen Preisen mitmischen oder der Konkurrenz davon galloppieren z.B. in Wiesbaden, Neum\u00fcnster, Hagen, Paderborn, Oliva, Luhm\u00fchlen,\u2026 Die schnellen Stechen haben uns beiden unendlich viel Spa\u00df gemacht!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aber auch der ganze Weg, die letzten 9 Jahre &#8211; Das t\u00e4gliche Training mit Goja\u2018s scheinbar unendlichem Bewegungsdrang und seiner ganz besonderen Pers\u00f6nlichkeit, die unser ganzes Team in seinen Bann gezogen hat!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich und wir Alle auf Hof Waterkant vermissen Dich jetzt schon sehr!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">An dieser Stelle m\u00f6chte ich mich auch bei Gojas langj\u00e4hrigem Besitzer, unserem Freund und Partner J\u00fcrgen Fitschen bedanken, dass er mir dieses au\u00dfergew\u00f6hnliche Pferd so viele Jahre anvertraut und zur Verf\u00fcgung gestellt hat!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Entscheidung unseren langj\u00e4hrigen vierbeinigen Partner aus dem Stall zu lassen, war sehr schwer, aber wir sind sicher, dass Goja als zuk\u00fcnftiger Lehrmeister bei unseren Freunden Familie Borho @metoliva ein wunderbares Leben und mit Carlos Borho Junior einen sehr talentierten jungen Reiter bekommt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Goja ist gern in der W\u00e4rme, mag gro\u00dfe Pl\u00e4tze und liebt es @metoliva am Strand durchs Wasser zu spazieren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich werde ihn oft besuchen und dem neuen Paar die Daumen dr\u00fccken und beiseite stehen!&#8221;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das war keine leichte Entscheidung f\u00fcr die ehemalige Mannschafts- Welt- und -Europameisterin Janne Friederike Meyer-Zimmermann: Gestern hat ihr ehemaliges Top-Pferd Goja (v. Wandor vd Mispelaere) den Hof Waterkant in Richtung Spanien verlassen. Der 16j\u00e4hrige Wallach wird k\u00fcnftig als Lehrmeister f\u00fcr einen Children-Reiter seinen Hafer verdienen. Janne Friederike Meyer-Zimmermann hat ihre &hellip; <a class=\"kt-excerpt-readmore\" href=\"https:\/\/www.spring-reiter.de\/en\/index.php\/2022\/01\/24\/janne-meyers-goja-wird-lehrpferd-in-spanien\/\" aria-label=\"Janne Meyers Goja wird Lehrpferd in Spanien!\">Read More<\/a><\/p>\n","protected":false},"author":2,"featured_media":48842,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-48840","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"en","enabled_languages":["de","en"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/www.spring-reiter.de\/en\/index.php\/wp-json\/wp\/v2\/posts\/48840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.spring-reiter.de\/en\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.spring-reiter.de\/en\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.spring-reiter.de\/en\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.spring-reiter.de\/en\/index.php\/wp-json\/wp\/v2\/comments?post=48840"}],"version-history":[{"count":0,"href":"https:\/\/www.spring-reiter.de\/en\/index.php\/wp-json\/wp\/v2\/posts\/48840\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.spring-reiter.de\/en\/index.php\/wp-json\/wp\/v2\/media\/48842"}],"wp:attachment":[{"href":"https:\/\/www.spring-reiter.de\/en\/index.php\/wp-json\/wp\/v2\/media?parent=48840"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.spring-reiter.de\/en\/index.php\/wp-json\/wp\/v2\/categories?post=48840"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.spring-reiter.de\/en\/index.php\/wp-json\/wp\/v2\/tags?post=48840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}