{"id":72802,"date":"2024-06-01T23:50:28","date_gmt":"2024-06-01T21:50:28","guid":{"rendered":"https:\/\/www.spring-reiter.de\/?p=72802"},"modified":"2024-06-01T23:50:32","modified_gmt":"2024-06-01T21:50:32","slug":"max-kuehner-wird-beim-sieg-im-grand-prix-in-st-tropez-von-max-verstappen-angefeuert","status":"publish","type":"post","link":"https:\/\/www.spring-reiter.de\/en\/index.php\/2024\/06\/01\/max-kuehner-wird-beim-sieg-im-grand-prix-in-st-tropez-von-max-verstappen-angefeuert\/","title":{"rendered":"Max K\u00fchner wird beim Sieg im Grand Prix in St. Tropez von Max Verstappen angefeuert"},"content":{"rendered":"\n<p>Max K\u00fchner und Eic Up Too Jacco Blue haben den Longines Global Champions Tour Grand Prix von St. Tropez gewonnen. Formel-1-Weltmeister Max Verstappen war dabei zum Anfeuern unter den Zuschauern. Der Zweite, Simon Delestre, lieferte sich auf Cayman Jolly Jumper ein Kopf-an-Kopf-Rennen mit dem derzeitigen LGCT-Meisterschaftsf\u00fchrenden Eduardo Alvarez Aznar, der sich auf dem 19-j\u00e4hrigen Rokfeller de Pleville Bois Margot den dritten Platz sicherte und seine Gesamtf\u00fchrung auf 18 Punkte ausbaute.<\/p>\n\n\n\n<p>Ein strahlender Max K\u00fchner sagte hinterher: \u201eEs ist gro\u00dfartig, wieder ganz oben auf einem Longines Global Champions Tour Grand Prix Podium zu stehen, besonders hier in Ramatuelle, wo Max Verstappen uns zusieht. Meine Pferde waren in dieser Saison so konstant, das macht es so spannend, Teil dieser Meisterschaft zu sein.&#8221;<\/p>\n\n\n\n<p>Lange sah es so aus, als ob es kein Stechen geben w\u00fcrde, bis Max K\u00fchner als 18. bewies, dass der anspruchsvolle Parcours fehlerfrei zu springen ist, und damit die 22 nachfolgenden Reiter herausforderte. Der letztj\u00e4hrige Gewinner des LGCT Grand Prix von Ramatuelle, Julien Epaillard, lieferte dann vor seinem Heimpublikum ebenfalls eine fehlerfreie Runde ab. <\/p>\n\n\n\n<p>Der derzeitige LGCT-Meisterschaftsf\u00fchrende Eduardo Alvarez Aznar kam mit Rokfeller de Pleville Bois Margot im Umlauf fehlerfrei ins Ziel. Der Spanier sicherte sich seinen f\u00fcnften Platz im Stechen in diesem Jahr und hatte damit die Chance, seine LGCT-Meisterschaft zu verteidigen. Auch der Franzose Simon Delestre sprang auf Cayman Jolly Jumper fehlerfrei. <\/p>\n\n\n\n<p>Mit einer extrem knappen Zeitvorgabe mussten Katrin Eckermann und Kim Emmen jeweils einen \u00e4rgerlichen Zeitfehler in Kauf nehmen, der sie aus dem Stechen heraushielt, aber dennoch eine Top 5-Platzierung im LGCT Grand Prix erm\u00f6glichte. Auch die Meisterschaftsanw\u00e4rter Julien Aquetin, Christian Kukuk und Andreas Schou konnten sich alle nicht f\u00fcr das Stechen qualifizieren.<\/p>\n\n\n\n<p>Das Stechen war ein Kopf-an-Kopf-Rennen zwischen den beiden F\u00fchrenden in der LGCT-Meisterschaftswertung, die sich in St. Tropez die maximale Punktzahl sichern wollten.<\/p>\n\n\n\n<p>Max K\u00fchner legte auf Eic Up Too Jacco Blue eine blitzschnelle Runde hin, wobei er am letzten Sprung vorsichtig war, um sicherzustellen, dass er sauber ins Ziel kam. Seine hervorragende Runde brachte ihn in einer Zeit von 36,39 Sekunden auf den ersten Platz, drei Reiter waren noch im Rennen.<\/p>\n\n\n\n<p>Der Gewinner des Grand Prix von Ramatuelle 2023, Julien Epaillard, wollte hier in St. Tropez seinen zweiten Sieg in Folge einfahren. Er bew\u00e4ltigte den Parcours schnell, aber der franz\u00f6sische Reiter sammelte acht Fehlerpunkte ein, was Platz vier bedeutete.<\/p>\n\n\n\n<p>Der F\u00fchrende der LGCT-Meisterschaft, Eduardo Alvarez Aznar, ritt mit Rokfeller de Pleville Bois Margot, der in f\u00fcnf aufeinanderfolgenden LGCT-Grand Prix fehlerfrei geblieben ist, im Stechen erneut fehlerfrei. Der Spanier war schnell, konnte aber das hohe Tempo von K\u00fchner nicht ganz mitgehen. Aznar konnte sich einen Platz auf dem Podium sichern und wurde schlie\u00dflich Dritter auf Rokfeller.<\/p>\n\n\n\n<p>Der letzte Starter, Simon Delestre, war auf der Jagd nach einem Sieg auf seinem Heimatplatz in St. Tropez. Der Franzose schwebte \u00fcber den Parcours, konnte aber Max K\u00fchner nicht ganz einholen und belegte in 37,74 Sekunden den zweiten Platz.<\/p>\n\n\n\n<p>Trotz seines dritten Platzes beh\u00e4lt Aznar seine F\u00fchrung in der LGCT-Meisterschaftswertung. Mit seinem Sieg in Ramatuelle schlie\u00dft K\u00fchner zu Aznar auf und liegt nun nur noch 18 Punkte hinter der Spitze.<\/p>\n\n\n\n<p>Das komplette Ergebnis <a href=\"https:\/\/www.longinestiming.com\/equestrian\/2024\/longines-global-champions-tour-of-st-tropez-ramatuelle-st-tropez\/resultlist_06.html\">hier<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Max K\u00fchner und Eic Up Too Jacco Blue haben den Longines Global Champions Tour Grand Prix von St. Tropez gewonnen. Formel-1-Weltmeister Max Verstappen war dabei zum Anfeuern unter den Zuschauern. Der Zweite, Simon Delestre, lieferte sich auf Cayman Jolly Jumper ein Kopf-an-Kopf-Rennen mit dem derzeitigen LGCT-Meisterschaftsf\u00fchrenden Eduardo Alvarez Aznar, der &hellip; <a class=\"kt-excerpt-readmore\" href=\"https:\/\/www.spring-reiter.de\/en\/index.php\/2024\/06\/01\/max-kuehner-wird-beim-sieg-im-grand-prix-in-st-tropez-von-max-verstappen-angefeuert\/\" aria-label=\"Max K\u00fchner wird beim Sieg im Grand Prix in St. Tropez von Max Verstappen angefeuert\">Read More<\/a><\/p>\n","protected":false},"author":3,"featured_media":72803,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-72802","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"en","enabled_languages":["de","en"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/www.spring-reiter.de\/en\/index.php\/wp-json\/wp\/v2\/posts\/72802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.spring-reiter.de\/en\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.spring-reiter.de\/en\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.spring-reiter.de\/en\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.spring-reiter.de\/en\/index.php\/wp-json\/wp\/v2\/comments?post=72802"}],"version-history":[{"count":0,"href":"https:\/\/www.spring-reiter.de\/en\/index.php\/wp-json\/wp\/v2\/posts\/72802\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.spring-reiter.de\/en\/index.php\/wp-json\/wp\/v2\/media\/72803"}],"wp:attachment":[{"href":"https:\/\/www.spring-reiter.de\/en\/index.php\/wp-json\/wp\/v2\/media?parent=72802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.spring-reiter.de\/en\/index.php\/wp-json\/wp\/v2\/categories?post=72802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.spring-reiter.de\/en\/index.php\/wp-json\/wp\/v2\/tags?post=72802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}