{"id":72957,"date":"2024-06-07T18:13:47","date_gmt":"2024-06-07T16:13:47","guid":{"rendered":"https:\/\/www.spring-reiter.de\/?p=72957"},"modified":"2024-06-07T18:13:50","modified_gmt":"2024-06-07T16:13:50","slug":"emilia-loeser-gewinnt-qualifikation-zur-deutschen-damen-meisterschaft","status":"publish","type":"post","link":"https:\/\/www.spring-reiter.de\/en\/index.php\/2024\/06\/07\/emilia-loeser-gewinnt-qualifikation-zur-deutschen-damen-meisterschaft\/","title":{"rendered":"Emilia L\u00f6ser gewinnt Qualifikation zur Deutschen Damen-Meisterschaft"},"content":{"rendered":"\n<p>Sie kam erst als 46. der 51 Starterinnen in den Parcours der Qualifikation zur Deutschen Damen-Meisterschaft in Balve, aber als sie raus ritt, hatte sie die F\u00fchrung \u00fcbernommen und gab sie auch nicht mehr her: Emilia L\u00f6ser war auf Dexter Bois Margot (v. Qlassic Bois Margot) in 71,48 Sekunden fehlerfrei durch den Stangenwald gefegt und sicherte sich damit die beste Ausgangsposition im Kampf um die Damen-Meisterschaft.<\/p>\n\n\n\n<p>Auf Platz zwei sprang Brit Haselhoff mit Katniss (v. Catoki) vor Stephi de Boer auf Querida (v. Qualito I). Auf Rang vier folgte Juliane R\u00f6lfing mit Come and feel O (v. Comme il faut) vor Sarah Welsing-Breuer auf Casado (v. Casall). Nat\u00fcrlich waren sie alle fehlerfrei in dem CSI*** \u00fcber 1,50m \u2013 genauso wie die folgenden Konkurrentinnen bis einschlie\u00dflich Platz 11. Es ist im Prinzip also noch (fast) alles offen vor dem Finale am morgigen Samstagnachmittag.<\/p>\n\n\n\n<p>Das komplette Ergebnis <a href=\"https:\/\/www.longinestiming.com\/equestrian\/2024\/longines-balve-optimum-balve\/resultlist_12.html\">hier<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sie kam erst als 46. der 51 Starterinnen in den Parcours der Qualifikation zur Deutschen Damen-Meisterschaft in Balve, aber als sie raus ritt, hatte sie die F\u00fchrung \u00fcbernommen und gab sie auch nicht mehr her: Emilia L\u00f6ser war auf Dexter Bois Margot (v. Qlassic Bois Margot) in 71,48 Sekunden fehlerfrei &hellip; <a class=\"kt-excerpt-readmore\" href=\"https:\/\/www.spring-reiter.de\/en\/index.php\/2024\/06\/07\/emilia-loeser-gewinnt-qualifikation-zur-deutschen-damen-meisterschaft\/\" aria-label=\"Emilia L\u00f6ser gewinnt Qualifikation zur Deutschen Damen-Meisterschaft\">Read More<\/a><\/p>\n","protected":false},"author":3,"featured_media":72962,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-72957","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"en","enabled_languages":["de","en"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/www.spring-reiter.de\/en\/index.php\/wp-json\/wp\/v2\/posts\/72957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.spring-reiter.de\/en\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.spring-reiter.de\/en\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.spring-reiter.de\/en\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.spring-reiter.de\/en\/index.php\/wp-json\/wp\/v2\/comments?post=72957"}],"version-history":[{"count":0,"href":"https:\/\/www.spring-reiter.de\/en\/index.php\/wp-json\/wp\/v2\/posts\/72957\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.spring-reiter.de\/en\/index.php\/wp-json\/wp\/v2\/media\/72962"}],"wp:attachment":[{"href":"https:\/\/www.spring-reiter.de\/en\/index.php\/wp-json\/wp\/v2\/media?parent=72957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.spring-reiter.de\/en\/index.php\/wp-json\/wp\/v2\/categories?post=72957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.spring-reiter.de\/en\/index.php\/wp-json\/wp\/v2\/tags?post=72957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}