{"id":73147,"date":"2024-06-13T17:58:36","date_gmt":"2024-06-13T15:58:36","guid":{"rendered":"https:\/\/www.spring-reiter.de\/?p=73147"},"modified":"2024-06-13T17:58:39","modified_gmt":"2024-06-13T15:58:39","slug":"trainiere-und-tue-gutes-charity-auktion-fuer-justworld-international-auf-hof-kasselmann","status":"publish","type":"post","link":"https:\/\/www.spring-reiter.de\/en\/index.php\/2024\/06\/13\/trainiere-und-tue-gutes-charity-auktion-fuer-justworld-international-auf-hof-kasselmann\/","title":{"rendered":"Trainiere und tue Gutes: Charity-Auktion f\u00fcr JustWorld International auf Hof Kasselmann"},"content":{"rendered":"\n<p>Am morgigen Freitag, den 14. Juni, f\u00e4llt der Hammer bei der dritten Hof Kasselmann &amp; Schockem\u00f6hle Hybrid-Auktion. Den Auftakt des Abends bildet eine Wohlt\u00e4tigkeitsauktion zugunsten von JustWorld International. Die internationale, gemeinn\u00fctzige Organisation ver\u00e4ndert das Leben von Kindern in verarmten Gemeinden auf der ganzen Welt, indem sie ihnen Zugang zu lebensver\u00e4ndernden Bildungs-, Gesundheits- und Ern\u00e4hrungsprogrammen verschafft.&nbsp;<\/p>\n\n\n\n<p>Zwei einzigartige Erlebnisse, die man mit Geld nicht kaufen kann, k\u00f6nnen bereits heute online ersteigert werden.\u00a0<strong>Der gesamte Erl\u00f6s kommt JustWorld International zugute. Trainieren Sie mit den Spitzenreitern und tun Sie gleichzeitig Gutes!!\u00a0<\/strong><\/p>\n\n\n\n<p><strong>F\u00fcr Springbegeisterte:<\/strong><\/p>\n\n\n\n<p><strong>3-Tage-Paket: T\u00e4glich eine Unterrichtsstunde mit Ludger Beerbaum<\/strong>, Gewinner von vier olympischen Goldmedaillen und zwei Mannschafts-WM-Goldmedaillen. Der Unterricht findet im Reitsportzentrum Riesenbeck International in Deutschland statt. Termine werden mit allen Beteiligten abgesprochen.<\/p>\n\n\n\n<p><strong>F\u00fcr Dressurliebhaber:<\/strong><\/p>\n\n\n\n<p><strong>3-Tage-Paket: T\u00e4glich eine Unterrichtsstunde mit Frederic Wandres<\/strong>, EM Silbermedaillengewinner mit der Mannschaft, der derzeit auf Platz 9 der FEI-Dressur-Weltrangliste steht. Der Unterricht findet auf dem Hof Kasselmann in Hagen a.T.W. oder auf der Anlage des Hof Kasselmann in Wellington, Florida statt. Termine werden mit allen Beteiligten abgesprochen.<\/p>\n\n\n\n<p>Gebote abgeben <a href=\"http:\/\/ximrj.mjt.lu\/lnk\/AW4AAEXAZAIAAABcxbAAAPOL-gMAAAAAngQAASfiABSxiwBmaxFyBAi5Y42jSNe1CnqgRgiP-AAUhl4\/2\/3eaIBOJUPn82Qq8adbk8Vw\/aHR0cHM6Ly9vbmxpbmUuaG9ma2Fzc2VsbWFubi1hdWN0aW9uLmNvbS9hdWN0aW9ucy84ZmVhODRmMi02MjNiLTQzZTAtNTMwYS0wOGRjOGI5ZTk3ZGE\">hier<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am morgigen Freitag, den 14. Juni, f\u00e4llt der Hammer bei der dritten Hof Kasselmann &amp; Schockem\u00f6hle Hybrid-Auktion. Den Auftakt des Abends bildet eine Wohlt\u00e4tigkeitsauktion zugunsten von JustWorld International. Die internationale, gemeinn\u00fctzige Organisation ver\u00e4ndert das Leben von Kindern in verarmten Gemeinden auf der ganzen Welt, indem sie ihnen Zugang zu lebensver\u00e4ndernden &hellip; <a class=\"kt-excerpt-readmore\" href=\"https:\/\/www.spring-reiter.de\/en\/index.php\/2024\/06\/13\/trainiere-und-tue-gutes-charity-auktion-fuer-justworld-international-auf-hof-kasselmann\/\" aria-label=\"Trainiere und tue Gutes: Charity-Auktion f\u00fcr JustWorld International auf Hof Kasselmann\">Read More<\/a><\/p>\n","protected":false},"author":3,"featured_media":73150,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-73147","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"en","enabled_languages":["de","en"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/www.spring-reiter.de\/en\/index.php\/wp-json\/wp\/v2\/posts\/73147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.spring-reiter.de\/en\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.spring-reiter.de\/en\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.spring-reiter.de\/en\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.spring-reiter.de\/en\/index.php\/wp-json\/wp\/v2\/comments?post=73147"}],"version-history":[{"count":0,"href":"https:\/\/www.spring-reiter.de\/en\/index.php\/wp-json\/wp\/v2\/posts\/73147\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.spring-reiter.de\/en\/index.php\/wp-json\/wp\/v2\/media\/73150"}],"wp:attachment":[{"href":"https:\/\/www.spring-reiter.de\/en\/index.php\/wp-json\/wp\/v2\/media?parent=73147"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.spring-reiter.de\/en\/index.php\/wp-json\/wp\/v2\/categories?post=73147"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.spring-reiter.de\/en\/index.php\/wp-json\/wp\/v2\/tags?post=73147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}