{"id":48670,"date":"2022-01-17T18:41:44","date_gmt":"2022-01-17T17:41:44","guid":{"rendered":"https:\/\/www.spring-reiter.de\/?p=48670"},"modified":"2022-01-17T18:41:48","modified_gmt":"2022-01-17T17:41:48","slug":"traditionsturnier-vr-classics-neumuenster-auf-2023-verschoben","status":"publish","type":"post","link":"https:\/\/www.spring-reiter.de\/index.php\/2022\/01\/17\/traditionsturnier-vr-classics-neumuenster-auf-2023-verschoben\/","title":{"rendered":"Traditionsturnier VR CLASSICS Neum\u00fcnster auf 2023 verschoben"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Die VR CLASSICS Neum\u00fcnster, die vom 16.-20. Februar 2022 in den Holstenhallen stattfinden sollten, werden auf das Jahr 2023 verschoben. &#8222;Das ist f\u00fcr die Pferdesportfans und auch f\u00fcr uns als Veranstalter eine gro\u00dfe Entt\u00e4uschung&#8220;, so Turnierchef Francois Kasselmann, &#8222;aber die aktuelle Situation der Corona-Pandemie l\u00e4sst keine andere Entscheidung zu.&#8220; Die gute Nachricht: Der FEI Dressage World Cup darf am 19. und 20. Februar in den Holstenhallen stattfinden &#8211; ohne Publikum vor Ort, aber im Livestream bei ClipMyHorse.TV verf\u00fcgbar.<br>Die stark gestiegenen Infektionszahlen der Omikron-Welle und die notwendigen Beschl\u00fcsse und konsequenten Ma\u00dfnahmen des Landes Schleswig-Holstein machen eine Durchf\u00fchrung der traditionellen VR CLASSICS in der vertrauten Form unm\u00f6glich.<br>\u201eBis zuletzt hatten wir alle M\u00f6glichkeiten in Betracht gezogen und gehofft, unserem einzigartigen begeisterungsf\u00e4higen Neum\u00fcnsteraner Publikum unbeschwerte, gesellige Stunden und unvergessene Momente bei absolutem Spitzensport in Springen und Dressur bieten zu d\u00fcrfen,&#8220; so Francois Kasselmann (Gesch\u00e4ftsf\u00fchrer der Horses and Dreams Entertainment GmbH).<br>Tats\u00e4chlich ist es ihm und dem Team allerdings gelungen, auf Initiative der aktiven Reiterinnen und Reiter und mit Unterst\u00fctzung privater M\u00e4zene aus dem Reitsport in einem gemeinsamen &#8222;Schulterschluss&#8220; mit dem Weltverband FEI, den langj\u00e4hrigen Sponsoren &amp; Partnern sowie der Stadt Neum\u00fcnster, den FEI Dressage World Cup in Neum\u00fcnster 2022 zu sichern.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201eWir sind sehr gl\u00fccklich, dass wir die Weltcup Station in Neum\u00fcnster als online Event in diesen schweren Zeiten durchf\u00fchren k\u00f6nnen\u201c, freut sich Francois Kasselmann.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ein durchaus wichtiges Signal sowohl f\u00fcr die Sportszene, als auch f\u00fcr den Weltverband FEI. Neum\u00fcnsters VR CLASSICS sind seit 1989 Weltcupstandort und das sollen sie nach dem Willen der Veranstalter auch in Zukunft bleiben. Das Tagesprogramm wird f\u00fcr die teilnehmenden Reiterinnen und Reiter um weitere Pr\u00fcfungen wie z.B. die internationale kleine Tour erg\u00e4nzt. Details dazu stehen in K\u00fcrze fest.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finale der BEMER Riders Tour in der &#8222;gr\u00fcnen&#8220; Saison<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Finale der BEMER Riders Tour findet im Rahmen der Horses &amp; Dreams meets Canada vom 20.-24. April in Hagen a.T.W. statt, das zugleich der Auftakt f\u00fcr die Tour Saison 2022 ist.<br>Bedanken m\u00f6chte sich das Team um die Turnierleiter Francois und Ullrich Kasselmann, sowie Bettina &amp; Paul Schockem\u00f6hle vor allem bei den Sponsoren und Partnern der VR CLASSICS, die seit vielen Jahren wie ein Fels hinter der Veranstaltung stehen und in gro\u00dfer Solidarit\u00e4t die notwendige R\u00fcckendeckung geben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201eBesonders betonen m\u00f6chte ich aber auch einmal die gro\u00dfe Flexibilit\u00e4t und Kooperationsbereitschaft von Dirk Iwersen und seinem Team der Holstenhallen, vor allem in den vergangenen zwei Jahren,\u201c so Bettina Schockem\u00f6hle, langj\u00e4hrige Organisationschefin.<br>Erworbene Tickets behalten G\u00fcltigkeit<br>Bereits f\u00fcr die VR CLASSICS 2022 erworbene Tickets behalten ihre G\u00fcltigkeit f\u00fcr die Veranstaltung 2023. Etliche Pferdesportfans hatten 2021 bereits Karten erworben. Sie d\u00fcrfen sich nun auf die VR CLASSICS 2023 vom 16.-19. Februar 2023 freuen. Weitere Informationen folgen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die VR CLASSICS Neum\u00fcnster, die vom 16.-20. Februar 2022 in den Holstenhallen stattfinden sollten, werden auf das Jahr 2023 verschoben. &#8222;Das ist f\u00fcr die Pferdesportfans und auch f\u00fcr uns als Veranstalter eine gro\u00dfe Entt\u00e4uschung&#8220;, so Turnierchef Francois Kasselmann, &#8222;aber die aktuelle Situation der Corona-Pandemie l\u00e4sst keine andere Entscheidung zu.&#8220; Die &hellip; <a class=\"kt-excerpt-readmore\" href=\"https:\/\/www.spring-reiter.de\/index.php\/2022\/01\/17\/traditionsturnier-vr-classics-neumuenster-auf-2023-verschoben\/\" aria-label=\"Traditionsturnier VR CLASSICS Neum\u00fcnster auf 2023 verschoben\">Weiterlesen<\/a><\/p>\n","protected":false},"author":3,"featured_media":48671,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-48670","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"de","enabled_languages":["de","en"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/posts\/48670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/comments?post=48670"}],"version-history":[{"count":0,"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/posts\/48670\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/media\/48671"}],"wp:attachment":[{"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/media?parent=48670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/categories?post=48670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/tags?post=48670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}