{"id":48890,"date":"2022-01-26T16:34:35","date_gmt":"2022-01-26T15:34:35","guid":{"rendered":"https:\/\/www.spring-reiter.de\/?p=48890"},"modified":"2022-01-26T16:34:41","modified_gmt":"2022-01-26T15:34:41","slug":"international-jumping-riders-club-olympia-format-bleibt-auf-der-tagesordnung","status":"publish","type":"post","link":"https:\/\/www.spring-reiter.de\/index.php\/2022\/01\/26\/international-jumping-riders-club-olympia-format-bleibt-auf-der-tagesordnung\/","title":{"rendered":"International Jumping Riders Club: Olympia-Format bleibt auf der Tagesordnung"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Der International Jumping Riders Club, der Zusammenschluss der weltbesten Springreiter, hat seine Erwartungen und Pl\u00e4ne f\u00fcr 2022 formuliert und klar gemacht, dass die Frage, ob es bei Olympia bei drei Reitern pro Mannschaft bleibt, unver\u00e4ndert auf der Tagesordnung steht:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8222;2021 war ein herausforderndes Jahr f\u00fcr die ganze Welt und nicht nur f\u00fcr die gesamte Reitsportbranche. Der International Jumping Riders Club bem\u00fchte sich, sein Bestes zu tun, um Reiter und ihre Aktivit\u00e4ten zu unterst\u00fctzen, ihre Pferde zu sch\u00fctzen und einerseits zu versuchen, die anstehenden Probleme zu l\u00f6sen, andererseits sich den pl\u00f6tzlich auftretenden neuen Herausforderungen zu stellen. Wir m\u00f6chten betonen, dass die dringendsten Probleme, die der Club bei der Unterst\u00fctzung unserer Reiter anspricht, enthalten sind:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Einfrieren der Ranglistenpunkte, als die Pandemie die Absage der Saison 2020 und Anfang 2021 erzwang.<\/li><li>Aktives Engagement bei der Bew\u00e4ltigung des tier\u00e4rztlichen Notfalls mit dem Herpesvirus in Valencia im vergangenen Februar, eine Situation, in der das IJRC Ma\u00dfnahmen ergriffen hat, indem es Tier\u00e4rzte nach Valencia entsandte, St\u00e4lle zur Verf\u00fcgung stellte, den Transport der Pferde organisierte und die Reiter finanziell unterst\u00fctzte.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Zu den erreichten und sich entwickelnden Zielen geh\u00f6ren au\u00dferdem:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Qualifikationsregeln. Dopingregeln, Medikamenten- und Verbotslisten.<\/li><li>Kontamination: rechtliche und labortechnische Aspekte, Stallsicherheit. Bef\u00e4higungsnachweis\/MER (Mindestvoraussetzungen f\u00fcr die Berechtigung).<\/li><li>Einladungssystem. CSI\/CSIO-Anforderungen.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">ROLEX IJRC TOP-10-FINALE<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Jahr endete mit der 20. Ausgabe des Rolex IJRC Top Ten Final in Genf; eine Veranstaltung, die nach ihrer pandemiebedingten Absage im Jahr 2020 mit gro\u00dfer Spannung erwartet wurde. Die Bedeutung, die die Rolex IJRC Top Ten im internationalen Szenario einnimmt, geht weit \u00fcber die eines Spitzenwettbewerbs, weit \u00fcber die endg\u00fcltige Rangliste hinaus. Aber es stellt eine pers\u00f6nliche, subjektive Zufriedenheit dar, da das Reiten bei diesem Event der kr\u00f6nende Moment in einem Jahr voller konstruktiver und konstanter Aktivit\u00e4ten ist. Es ist das Ergebnis bestm\u00f6glicher Planung und Pferdef\u00fchrung. Die Teilnahme an den Rolex IJRC Top 10 ist ein Moment der positiven Wettbewerbsf\u00e4higkeit, des Zusammenhalts und, wenn noch m\u00f6glich, des weiteren Wachstums unter den zehn besten Fahrern der Welt, die das Beispiel f\u00fcr all die jungen Reiter geben, die jetzt ihre Karriere aufbauen. Ein Sieg der Olympiasieger Ben Maher und Explosion W best\u00e4tigt einfach ihre unvergessliche Saison, ohne die au\u00dfergew\u00f6hnliche Leistung aller Konkurrenten zu schm\u00e4lern; wahre Meister des echten Reitsports.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Generalversammlung des IJRC<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dar\u00fcber hinaus war Genf Gastgeber der \u00fcblichen Generalversammlung des IJRC, die Kevin Staut einstimmig als Pr\u00e4sidenten best\u00e4tigte; Emilio Bicocchi ersetzt Peder Fredricson. Die best\u00e4tigten Vorstandsmitglieder sind: Steve Guerdat, Fran\u00e7ois Mathy, Henrick von Eckermann, Rodrigo Pessoa, Max Kuhner und Ludger Beerbaum, zusammen mit einem Vertreter der NARG (North American Riders Group). Der Athletenvertreter ist Pedro Veniss.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lang- und kurzfristige Ziele<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">W\u00e4hrend dieses neue Jahr f\u00fcr uns alle beginnt, bleibt es voller Probleme, die leider immer noch mit der Pandemie verbunden sind, was wiederum zur Absage zahlreicher Shows in diesen ersten Monaten f\u00fchrt. Dennoch wird 2022 das Jahr der Herning-Weltmeisterschaften vom 6. bis 14. August, einer Veranstaltung, die den Weg f\u00fcr die Qualifikation f\u00fcr die Olympischen Spiele 2024 in Paris ebnet. Zu diesem Thema ist eine der Hauptabsichten des Clubs, die immer noch hitzige Debatte \u00fcber das Qualifikationssystem, das olympische Format und das FEI-Wahlsystem zu l\u00f6sen und Harmonie und Synergie mit den Institutionen zum Wohle unseres einzigartigen und unnachahmlichen Sports herzustellen. Mit Weitblick und einem globalen Blick auf die Bed\u00fcrfnisse aller beteiligten Professionalit\u00e4ten ist das Ziel, dass die Olympischen Spiele weiterhin der gr\u00f6\u00dfte Traum aller Athleten bleiben, so wie sie es sein sollten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zu unseren Vors\u00e4tzen f\u00fcr das neue Jahr geh\u00f6rt es au\u00dferdem, die Prinzipien, auf deren Grundlage dieser Club entstanden ist und dank denen er immer mehr Athleten anzieht, weiter konkret zu verbreiten. Vor allem junge Menschen, die im IJRC einen Anlaufpunkt finden, an dem Themen diskutiert und Unterst\u00fctzung f\u00fcr ihre neue Karriere gefunden werden k\u00f6nnen. Der Club hat seine Regeln, Initiativen und Aktivit\u00e4ten, die f\u00fcr die Entwicklung von Pferden und Reitern n\u00fctzlich sind.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ein solches Beispiel ist die Zusammenarbeit des IJRC mit der Young Riders Academy. Es bietet nicht nur eine gro\u00dfartige Gelegenheit f\u00fcr technisches und professionelles Wachstum, sondern auch f\u00fcr den Meinungsaustausch zwischen erfahrenen Reitern und den neuen Generationen. Der Nachwuchs steht zwar im Mittelpunkt und ist Tr\u00e4ger innovativer Ideen und neuer Energie, betont aber auch die spezifischen Bed\u00fcrfnisse f\u00fcr den Aufbau einer Karriere.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">EEF<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nicht zuletzt, auch dank der Planung der Nationenpreisserie der EEF f\u00fcr die neue Saison, unterst\u00fctzt der Club stark den Teamgeist und m\u00f6chte den neuen Generationen die Bedeutung von Einheit, Zusammenarbeit und Interaktion vermitteln, um den Weg f\u00fcr eine stabile Karriere zu ebnen voller Zufriedenheit und Wachstum des Reitsports. Daher ist unsere Arbeit darauf ausgerichtet, unsere Athleten und den gesamten Springsportsektor kontinuierlich zu unterst\u00fctzen. Die St\u00e4rke des IJRC liegt im Zusammenhalt aller seiner Mitglieder, die gemeinsam ihren Beitrag leisten mit innovative Ideen f\u00fcr die Weiterentwicklung unseres Sports.&#8220;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der International Jumping Riders Club, der Zusammenschluss der weltbesten Springreiter, hat seine Erwartungen und Pl\u00e4ne f\u00fcr 2022 formuliert und klar gemacht, dass die Frage, ob es bei Olympia bei drei Reitern pro Mannschaft bleibt, unver\u00e4ndert auf der Tagesordnung steht: &#8222;2021 war ein herausforderndes Jahr f\u00fcr die ganze Welt und nicht &hellip; <a class=\"kt-excerpt-readmore\" href=\"https:\/\/www.spring-reiter.de\/index.php\/2022\/01\/26\/international-jumping-riders-club-olympia-format-bleibt-auf-der-tagesordnung\/\" aria-label=\"International Jumping Riders Club: Olympia-Format bleibt auf der Tagesordnung\">Weiterlesen<\/a><\/p>\n","protected":false},"author":3,"featured_media":48891,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-48890","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"de","enabled_languages":["de","en"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/posts\/48890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/comments?post=48890"}],"version-history":[{"count":0,"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/posts\/48890\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/media\/48891"}],"wp:attachment":[{"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/media?parent=48890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/categories?post=48890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/tags?post=48890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}