{"id":48927,"date":"2022-01-27T17:10:05","date_gmt":"2022-01-27T16:10:05","guid":{"rendered":"https:\/\/www.spring-reiter.de\/?p=48927"},"modified":"2022-01-27T17:10:08","modified_gmt":"2022-01-27T16:10:08","slug":"dreijaehrige-dsp-hengste-freitag-und-samstag-bei-den-online-auktionen","status":"publish","type":"post","link":"https:\/\/www.spring-reiter.de\/index.php\/2022\/01\/27\/dreijaehrige-dsp-hengste-freitag-und-samstag-bei-den-online-auktionen\/","title":{"rendered":"Dreij\u00e4hrige DSP-Hengste Freitag und Samstag bei den Online-Auktionen"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Am letzten Wochenende stellten sich in M\u00fcnchen auf der Olympia-Reitanlage insgesamt 81 Hengste dem Urteil der K\u00f6rkommission. Jetzt stehen die sportiv aufgemachten dreij\u00e4hrigen Youngster einmal mehr im Rampenlicht bei den Online-Auktionen am Freitag, 28. Januar f\u00fcr die Spring- und am 29. Januar f\u00fcr die Dressurhengste. Gro\u00dfes internationales Interesse spiegelt sich bereits auf der Online-Plattform, <a href=\"http:\/\/dsp.horse24.com\" target=\"_blank\" rel=\"noreferrer noopener\">dsp.horse24.com<\/a>. Im bereits laufenden Bietverfahren wechseln sich zahlreich die L\u00e4nderfahnen aus aller Welt ab.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Im Springlot steht allen voran der Siegerhengst von Casino Grande \u2013 Havana Club, gefolgt von den Pr\u00e4mienhengsten abstammend von Askari, Diamant de Semilly, Herakles, Nixon van het Meulenhof und Uno I. Der aktuell unter der Deutschen Meisterin Sophie Hinners erfolgreiche Million Dollar ist mit zwei S\u00f6hnen in der Auktion vertreten. Ebenso Taloubet Z, Eldorado van de Zeshoek und Emerald van het Ruytershof. Von allen Youngstern sind neue Freispringvideos von den K\u00f6rtagen online. Man darf gespannt sein auf den Freitagabend, wenn um 19.30 Uhr das Bid up, die finale Auktionsphase, startet, noch passieren wird.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Einen Tag sp\u00e4ter, am Samstag, dem 29. Januar 2022, stehen ab 19.30 Uhr \u00fcber 40 dreij\u00e4hrige Dressurstars im Rampenlicht auf <a href=\"http:\/\/dsp.horse24.com\" target=\"_blank\" rel=\"noreferrer noopener\">dsp.horse24.com<\/a>. Gleich zum Auftakt steht der lackschwarze Beau abstammend vom DSP-Pr\u00e4mienhengst Don Royal im virtuellen Auktionsring. Der Siegerhengst gl\u00e4nzt mit drei Top-Grundgangarten und besticht die Frauenherzen mit viel Adel. Ihm folgen die Bewegungsgenie aus dem Pr\u00e4mienlot, deren V\u00e4ter Benicio, Fair Game, F\u00fcrst Samarant, Maracan\u00e1, Top Gear, Vitalis und Zackerey sind. Ein direkter Sohn des Totilas, zwei S\u00f6hne von Escamillo, Baron, Falihandro, Dream Boy, Jovian, Sir Donnerhall I und Toto JR stehen unter anderem zum Verkauf. Hei\u00df begehrt sind die hoch rittigen Nachkommen des Bundeschampions und Vize-Weltmeisters Secret. Der Rappe ist allein mit drei S\u00f6hnen im Auktionslot pr\u00e4sent. Auch der frisch gek\u00fcrte DSP-Elitehengst Millennium ist mit einem lackschwarzen gek\u00f6rten Sohn im Lot vertreten. Von allen Hengsten sind neue Videos vom Freilaufen und vom Longieren auf der Auktionsplattform zu finden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zahlreiche Auktionsaspiranten hatten diese Woche noch pers\u00f6nlichen Kundenbesuch: Viele Interessenten nutzten die Zeit, um sich pers\u00f6nliche Eindr\u00fccke von ihrem Zukunftsstar im Ausbildungsstall zu holen. Ausk\u00fcnfte zu den K\u00f6rkandidaten kann man sich auch bei DSP-Vermarktungsleiter Fritz Fleischmann einholen. Aber Vorsicht \u2013 wenn er einmal anf\u00e4ngt zu schw\u00e4rmen, dauert es bei dieser Kollektion sehr lange! Seine Telefonnummer: +49 151\/53115783<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am letzten Wochenende stellten sich in M\u00fcnchen auf der Olympia-Reitanlage insgesamt 81 Hengste dem Urteil der K\u00f6rkommission. Jetzt stehen die sportiv aufgemachten dreij\u00e4hrigen Youngster einmal mehr im Rampenlicht bei den Online-Auktionen am Freitag, 28. Januar f\u00fcr die Spring- und am 29. Januar f\u00fcr die Dressurhengste. Gro\u00dfes internationales Interesse spiegelt sich &hellip; <a class=\"kt-excerpt-readmore\" href=\"https:\/\/www.spring-reiter.de\/index.php\/2022\/01\/27\/dreijaehrige-dsp-hengste-freitag-und-samstag-bei-den-online-auktionen\/\" aria-label=\"Dreij\u00e4hrige DSP-Hengste Freitag und Samstag bei den Online-Auktionen\">Weiterlesen<\/a><\/p>\n","protected":false},"author":3,"featured_media":48761,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-48927","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"de","enabled_languages":["de","en"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/posts\/48927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/comments?post=48927"}],"version-history":[{"count":0,"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/posts\/48927\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/media\/48761"}],"wp:attachment":[{"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/media?parent=48927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/categories?post=48927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/tags?post=48927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}