{"id":72820,"date":"2024-06-02T21:44:59","date_gmt":"2024-06-02T19:44:59","guid":{"rendered":"https:\/\/www.spring-reiter.de\/?p=72820"},"modified":"2024-06-03T10:20:16","modified_gmt":"2024-06-03T08:20:16","slug":"schleifenregen-fuer-deutschen-nachwuchs-in-zuidwolde-und-samorin","status":"publish","type":"post","link":"https:\/\/www.spring-reiter.de\/index.php\/2024\/06\/02\/schleifenregen-fuer-deutschen-nachwuchs-in-zuidwolde-und-samorin\/","title":{"rendered":"Schleifenregen f\u00fcr deutschen Nachwuchs in Zuidwolde und Samorin!"},"content":{"rendered":"\n<p>Nach den erfolgreichen Nationenpreisen ging es f\u00fcr die deutschen Children, Junioren und Jungen Reiter noch einmal einzeln in die Grands Prix beim CSIO Youth Zuidwolde und bei der Danube Champions Tour in Samorin. In beiden Turnierorten regnete es erneut Schleifen f\u00fcr den deutschen Nachwuchs.<\/p>\n\n\n\n<p>Zum Auftakt in Zuidwolde gewann Brianne Beerbaum auf Carrero T Z (v. Carrera VDL) Silber im Stechen des Grand Prix der Children \u2013 mit Doppelnull und nur eine Viertelsekunde langsamer als der siegreiche Italiener Andrea Pisani auf Charlemagne Jt Z (v. Cachas). Pech hatte Emma Hertz-Eichenrode, die auf Vienna (v. Viscount) zwar ebenfalls eine Doppelnull ablieferte, aber wegen ihrer Zeit knapp aus dem Geld rutschte.<\/p>\n\n\n\n<p>Im Stechen um den Grand Prix der Junioren war Max Merschformann auf Dorotheental\u2019s Classica (v.Hermes de Hus) zwar schneller als die sp\u00e4tere Siegerin Olivia Alvarez Garcia auf Cartouche, aber eine rollende Stange unterwegs lie\u00df ihn auf Rang 5 rutschen. Ebenfalls ins Geld sprangen Leonie Pander auf Plot Green und Ava Ferch auf Chacco-Mo.<\/p>\n\n\n\n<p>Im abschlie\u00dfenden Grand Prix der Jungen Reiter \u00fcber 1,45m verhinderten im Stechen acht Hundertstel den Sieg von Johanna Beckmann. So wurde sie auf Queen Frieda mit Doppelnull Zweite hinter Evelyne Putters auf Oberon VDH. Zweite Deutsche im Stechen war Marie Flick auf DSP Charlott. Zwei Springfehler unterwegs ergaben f\u00fcr sie Rang sechs.<\/p>\n\n\n\n<p>Bereits am Samstag hatte ein Grand Prx der Jungen Reiter \u00fcber 1,35m einen deutschen Doppelsieg gesehen: Mick Haunhorst gewann auf DSP Undercover im Stechenmit 14 Hundertstel Vorsprung vor Magnus Schmidt auf Bella D\u2019Or. Doppelnull waren sie beide.<\/p>\n\n\n\n<p>In Samorin feierte Luise Konle den gr\u00f6\u00dften Erfolg: Auf Dressed for Success war sie im Stechen der sieben Qualifizierten die schnellste Doppelnullerin und holte sich den Sieg im Grand Prix der Junioren. Nach einem Abwurf im Stechen platzierte sich Charlotte Westphal mit Cara als Siebte. Bei den Jungen Reiter sprang Ben Heckmann im Stechen des Grand Prix mit Mabaloe auf Platz f\u00fcnf, kam sogar auch noch mit seinem zweiten Pferd Son of a Gun ins Stechen und wurde zus\u00e4tzlich auch Siebter.<\/p>\n\n\n\n<p>Alle Ergebnisse aus Zuidwolde <a href=\"https:\/\/result.scgvisual.com\/show\/151\/schedule\/?date=2024-06-02\">hier<\/a><\/p>\n\n\n\n<p>Alle Ergebnisse aus Samorin <a href=\"https:\/\/www.ridersanddreams.sk\/24dcht6lists\">hier<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nach den erfolgreichen Nationenpreisen ging es f\u00fcr die deutschen Children, Junioren und Jungen Reiter noch einmal einzeln in die Grands Prix beim CSIO Youth Zuidwolde und bei der Danube Champions Tour in Samorin. In beiden Turnierorten regnete es erneut Schleifen f\u00fcr den deutschen Nachwuchs. Zum Auftakt in Zuidwolde gewann Brianne &hellip; <a class=\"kt-excerpt-readmore\" href=\"https:\/\/www.spring-reiter.de\/index.php\/2024\/06\/02\/schleifenregen-fuer-deutschen-nachwuchs-in-zuidwolde-und-samorin\/\" aria-label=\"Schleifenregen f\u00fcr deutschen Nachwuchs in Zuidwolde und Samorin!\">Weiterlesen<\/a><\/p>\n","protected":false},"author":3,"featured_media":72847,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-72820","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"de","enabled_languages":["de","en"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/posts\/72820","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/comments?post=72820"}],"version-history":[{"count":0,"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/posts\/72820\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/media\/72847"}],"wp:attachment":[{"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/media?parent=72820"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/categories?post=72820"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/tags?post=72820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}