{"id":72973,"date":"2024-06-07T18:44:36","date_gmt":"2024-06-07T16:44:36","guid":{"rendered":"https:\/\/www.spring-reiter.de\/?p=72973"},"modified":"2024-06-07T18:44:37","modified_gmt":"2024-06-07T16:44:37","slug":"post-von-der-fei-stuttgart-bleibt-mindestens-bis-2027-weltcup-station","status":"publish","type":"post","link":"https:\/\/www.spring-reiter.de\/index.php\/2024\/06\/07\/post-von-der-fei-stuttgart-bleibt-mindestens-bis-2027-weltcup-station\/","title":{"rendered":"Post von der FEI: Stuttgart bleibt (mindestens) bis 2027 Weltcup-Station!"},"content":{"rendered":"\n<p>Die Post aus Lausanne ist unterzeichnet von der Generalsekret\u00e4rin des Weltverbandes FEI, Sabrina Ib\u00e1\u00f1ez. Und die l\u00f6ste beim Organisationsteam der STUTTGART GERMAN MASTERS Freude aus: Die F\u00e9d\u00e9ration Equestre Internationale hat die Vergabe der Weltcup-Qualifikationen f\u00fcr 2025 im Springen, in der Dressur und im Viererzugfahren sowie im \u201ekleinen\u201c Pendant bei den Ponies um die FEI Jumping Ponies TrophyTM bekannt gegeben. Im Springen gastiert der Longines FEI Jumping World CupTM sogar bis einschlie\u00dflich 2027 in Stuttgart. \u201eWir sind stolz darauf, dass die FEI uns auch f\u00fcr das n\u00e4chste Jahr mit der Ausrichtung der verschiedenen Weltcup-Qualifikationen betraut\u201c, betont Andreas Kroll, der Gesch\u00e4ftsf\u00fchrer der in.Stuttgart Veranstaltungsgesellschaft. \u201eSo k\u00f6nnen wir unserem treuen Publikum auch im kommenden Jahr Pferdesport der Spitzenklasse pr\u00e4sentieren.\u201c<\/p>\n\n\n\n<p>F\u00fcr dieses Jahr \u2013 vom 13. bis 17. November 2024 \u2013 kosten die Einzelkarten f\u00fcr das Reitsport-Highlight zwischen 9 und 65 Euro, Tageskarten zwischen 35 und 86 Euro. Dauerkarten sind zum Preis von 189, 236 und 258 Euro erh\u00e4ltlich. Eintrittskarten f\u00fcr das 38. Internationale Reitturnier STUTTGART GERMAN MASTERS gibt es \u00fcber den Easy Ticket Service, Telefon 0711 25555-55, an allen bekannten Vorverkaufsstellen sowie \u00fcber das Internet www.easyticket.de, alle Preise inklusive Vorverkaufsgeb\u00fchren und Versand.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Post aus Lausanne ist unterzeichnet von der Generalsekret\u00e4rin des Weltverbandes FEI, Sabrina Ib\u00e1\u00f1ez. Und die l\u00f6ste beim Organisationsteam der STUTTGART GERMAN MASTERS Freude aus: Die F\u00e9d\u00e9ration Equestre Internationale hat die Vergabe der Weltcup-Qualifikationen f\u00fcr 2025 im Springen, in der Dressur und im Viererzugfahren sowie im \u201ekleinen\u201c Pendant bei den &hellip; <a class=\"kt-excerpt-readmore\" href=\"https:\/\/www.spring-reiter.de\/index.php\/2024\/06\/07\/post-von-der-fei-stuttgart-bleibt-mindestens-bis-2027-weltcup-station\/\" aria-label=\"Post von der FEI: Stuttgart bleibt (mindestens) bis 2027 Weltcup-Station!\">Weiterlesen<\/a><\/p>\n","protected":false},"author":3,"featured_media":68158,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-72973","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"de","enabled_languages":["de","en"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/posts\/72973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/comments?post=72973"}],"version-history":[{"count":0,"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/posts\/72973\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/media\/68158"}],"wp:attachment":[{"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/media?parent=72973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/categories?post=72973"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/tags?post=72973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}