{"id":73044,"date":"2024-06-09T18:39:51","date_gmt":"2024-06-09T16:39:51","guid":{"rendered":"https:\/\/www.spring-reiter.de\/?p=73044"},"modified":"2024-06-09T18:39:55","modified_gmt":"2024-06-09T16:39:55","slug":"es-lief-vom-allerfeinsten-hier-fuer-michpatrick-stuehlmeyer-drako-de-maugre-sind-die-deutschen-meister-2024","status":"publish","type":"post","link":"https:\/\/www.spring-reiter.de\/index.php\/2024\/06\/09\/es-lief-vom-allerfeinsten-hier-fuer-michpatrick-stuehlmeyer-drako-de-maugre-sind-die-deutschen-meister-2024\/","title":{"rendered":"&#8222;Es lief vom Allerfeinsten hier f\u00fcr mich!&#8220;Patrick St\u00fchlmeyer &amp; Drako de Maugre sind die Deutschen Meister 2024"},"content":{"rendered":"\n<p>Er kam aus dem Strahlen gar nicht mehr raus. Und so richtig konnte er seinen Triumph auch noch gar nicht in Worte fassen. Patrick St\u00fchlmeyer und Drako de Maugre (v. Kannan) blieben bei der Deutschen Meisterschaft in Balve als Einzige \u00fcber vier Runden fehlerfrei. Das war der klare Sieg.<\/p>\n\n\n\n<p>&#8222;Das ist mein bisher gr\u00f6\u00dfter Erfolg. Ich war die letzten Jahre immer dicht dran. Mit Drako de Maugre habe ich dieses Jahr ein Top-Pferd. Wir haben in den letzten Wochen mit Andreas Kreuzer viel an der Rittigkeit gearbeitet. Denn oft hatten wir kleine Fl\u00fcchtigkeitsfehler. Hier in Balve lief es vom Allerfeinsten f\u00fcr mich&#8220;, freute sich Patrick St\u00fchlmeyer nach seinem Sieg. Er sitzt seit zwei Jahren im Sattel des Fuchs-Hengstes, den das Team in Frankreich entdeckt hat. &#8222;Drako ist sehr schlau und intelligent. Er macht kein gro\u00dfes Spektakel am Sprung, aber er wei\u00df genau, wo die Stange h\u00e4ngt&#8220;, erz\u00e4hlt der neue Deutsche Meister. Mit dem Sieg hat er auch das Ticket f\u00fcr Aachen gel\u00f6st, best\u00e4tigte Bundestrainer Marcus D\u00f6ring. &#8222;Auf Aachen freue ich mich riesig, weil Drako gro\u00dfe Rasenpl\u00e4tze sehr liebt&#8220;, sagte Patrick St\u00fchlmeyer, der jetzt erst einmal mit einer &#8222;Jungs-Truppe&#8220; in den Urlaub nach Mallorca fahren wird.<\/p>\n\n\n\n<p>Vize-Meister bei den Deutschen Meisterschaften wurde Cedric Wolf mit DSP Chicitito (v. Crossfire) und nur einem einzigen Zeitfehler \u00fcber die vier schweren Meisterschafts-Runden. &#8222;Das war jetzt schon ein gro\u00dfer Schritt f\u00fcr mich, Silber bei den Senioren zu gewinnen&#8220;, erz\u00e4hlte der 26-J\u00e4hrige. Lange hatte er gar nicht gewusst, ob er \u00fcberhaupt an den Start gehen konnte. &#8222;Mein Pferd war seit Januar nicht richtig fit. Seine Knie waren entz\u00fcndet und wir haben ihn behandeln lassen. Die Genesung hat sich dann doch l\u00e4nger hingezogen, und es war gar nicht klar, ob ich nach Balve kommen w\u00fcrde. Jetzt bin ich nat\u00fcrlich sehr froh, dass er sich wieder so fit gezeigt hat&#8220;, erz\u00e4hlt Cedric Wolf.<\/p>\n\n\n\n<p>Dritte auf dem Meister-Podium wurden die Meister von 2022, Mario Stevens und Starissa (v. Stakkato Gold). &#8222;Der eine Fehler am ersten Tag war sehr \u00e4rgerlich, weil es ein reiner Reiter-Fehler war. Starissa ist super gesprungen. Auch an allen anderen Tagen. Daher bin ich mit Platz drei zufrieden. Ich komme so gerne nach Balve, es ist ein Highlight f\u00fcr mich und meine Familie. Ich liebe dieses Turnier&#8220;, gestand Mario Stevens zum Abschluss.<\/p>\n\n\n\n<p>Das ganze Ergebnis: <a href=\"https:\/\/results.hippodata.de\/2024\/2437\/docs\/r_dm_endstand.pdf\">HIER<\/a> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Er kam aus dem Strahlen gar nicht mehr raus. Und so richtig konnte er seinen Triumph auch noch gar nicht in Worte fassen. Patrick St\u00fchlmeyer und Drako de Maugre (v. Kannan) blieben bei der Deutschen Meisterschaft in Balve als Einzige \u00fcber vier Runden fehlerfrei. Das war der klare Sieg. &#8222;Das &hellip; <a class=\"kt-excerpt-readmore\" href=\"https:\/\/www.spring-reiter.de\/index.php\/2024\/06\/09\/es-lief-vom-allerfeinsten-hier-fuer-michpatrick-stuehlmeyer-drako-de-maugre-sind-die-deutschen-meister-2024\/\" aria-label=\"&#8222;Es lief vom Allerfeinsten hier f\u00fcr mich!&#8220;Patrick St\u00fchlmeyer &amp; Drako de Maugre sind die Deutschen Meister 2024\">Weiterlesen<\/a><\/p>\n","protected":false},"author":2,"featured_media":73050,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-73044","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"de","enabled_languages":["de","en"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/posts\/73044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/comments?post=73044"}],"version-history":[{"count":0,"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/posts\/73044\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/media\/73050"}],"wp:attachment":[{"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/media?parent=73044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/categories?post=73044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/tags?post=73044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}