{"id":73444,"date":"2024-06-27T17:37:19","date_gmt":"2024-06-27T15:37:19","guid":{"rendered":"https:\/\/www.spring-reiter.de\/?p=73444"},"modified":"2024-06-27T17:37:22","modified_gmt":"2024-06-27T15:37:22","slug":"jetzt-entdecken-kollektion-der-oldenburger-fohlenaukion","status":"publish","type":"post","link":"https:\/\/www.spring-reiter.de\/index.php\/2024\/06\/27\/jetzt-entdecken-kollektion-der-oldenburger-fohlenaukion\/","title":{"rendered":"Jetzt entdecken: Kollektion der Oldenburger Fohlenaukion"},"content":{"rendered":"\n<p>Sind Sie auf der Suche nach einer Nachwuchshoffnung f\u00fcr das Dressurviereck oder den Springparcours? Dann werfen Sie jetzt einen Blick in unsere Kollektion der 2. Oldenburger Online-Fohlenauktion, die am 12. Juli stattfindet, und verlieben Sie sich schon jetzt in ihren Favoriten!<\/p>\n\n\n\n<p>23 vielversprechende dressur- und springbetonte Fohlen warten am 12. Juli gespannt auf Ihr Gebot. Die Fohlen der 2. Oldenburger Online-Fohlenauktion zeichnen sich durch leistungsstarke Stutenst\u00e4mme aus, die bereits etliche internationale Sportpferde hervorgebracht haben. Auch v\u00e4terlicherseits \u00fcberzeugen die Pedigrees mit bedeutenden Vererbern wie dem Stempelhengst Nabab de Reve, dem belgischen Shootingstar Ermitage Kalone, dem Grand Prix-Sieger Uricas v.d. Kattevennen und dem Spitzenpferdelieferant Diarado. Oldenburger Siegerhengst Tobaro feiert ebenfalls sein Vererberdeb\u00fct. Zudem pr\u00e4sentieren&nbsp; renommierte Dressurv\u00e4ter wie die Oldenburger Siegerhengste Bonds und Fynch Hatton, ebenfalls Bundeschampion, sowie der Weltmeister Glamourdale ihren Nachwuchs.<\/p>\n\n\n\n<p>Erste Gebote k\u00f6nnen am Dienstag, 9. Juli um 12.00 Uhr, abgegeben werden. Das finale Bid-Up beginnt am Auktionstag, 12. Juli um 19.00 Uhr.<\/p>\n\n\n\n<p>Hier finden Sie einen \u00dcberblick \u00fcber die gesamte Kollektion: <a href=\"http:\/\/www.oldenburger-auktion.com\">www.oldenburger-auktion.com<\/a><\/p>\n\n\n\n<p>Bitte beachten Sie, dass diese Auktion ausschlie\u00dflich online \u00fcber die Plattform HORSE24 abl\u00e4uft. Falls Sie noch keinen g\u00fcltigen Account bei HORSE24 besitzen, registrieren Sie sich bitte vorab.<\/p>\n\n\n\n<p><strong>Beratung und Kundenservice:<\/strong><\/p>\n\n\n\n<p><strong>Auktionsleiter und Gesch\u00e4ftsf\u00fchrer Oldenburger Pferde-Vermarktungs GmbH:<\/strong><strong><br><\/strong>Roland Metz: +49(0)171-4364651 oder <a href=\"http:\/\/metz.roland@oldenburger-pferde.com\">metz.roland@oldenburger-pferde.com<\/a><\/p>\n\n\n\n<p><strong>Dressurpferde:<\/strong><strong><br><\/strong>Thomas Rhinow: +49(0)172-9748487 oder <a href=\"mailto:rhinow.thomas@oldenburger-pferde.com\">rhinow.thomas@oldenburger-pferde.com<br><\/a>Daniel Pophanken: +49(0)175-2930926 oder <a href=\"mailto:pophanken.daniel@oldenburger-pferde.com\">pophanken.daniel@oldenburger-pferde.com<\/a><\/p>\n\n\n\n<p><strong>Springpferde:<\/strong><br>Philip B\u00f6lle:&nbsp;+49(0)171-1893792 oder&nbsp;<a href=\"mailto:boelle.philip@oldenburger-pferde.com\">boelle.philip@oldenburger-pferde.com<br><\/a>Benjamin Stratmann: +49(0)151-54408395 oder <a href=\"mailto:stratmann.benjamin@oldenburger-pferde.com\">stratmann.benjamin@oldenburger-pferde.com<\/a><\/p>\n\n\n\n<p><strong>HORSE24 Support-Team:<\/strong><strong><br><\/strong>Tel.<strong>&nbsp;<\/strong>+49(0)172-7267334 oder&nbsp;<a href=\"mailto:support@horse24.com\">support@horse24.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sind Sie auf der Suche nach einer Nachwuchshoffnung f\u00fcr das Dressurviereck oder den Springparcours? Dann werfen Sie jetzt einen Blick in unsere Kollektion der 2. Oldenburger Online-Fohlenauktion, die am 12. Juli stattfindet, und verlieben Sie sich schon jetzt in ihren Favoriten! 23 vielversprechende dressur- und springbetonte Fohlen warten am 12. &hellip; <a class=\"kt-excerpt-readmore\" href=\"https:\/\/www.spring-reiter.de\/index.php\/2024\/06\/27\/jetzt-entdecken-kollektion-der-oldenburger-fohlenaukion\/\" aria-label=\"Jetzt entdecken: Kollektion der Oldenburger Fohlenaukion\">Weiterlesen<\/a><\/p>\n","protected":false},"author":3,"featured_media":73445,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-73444","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"de","enabled_languages":["de","en"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/posts\/73444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/comments?post=73444"}],"version-history":[{"count":0,"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/posts\/73444\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/media\/73445"}],"wp:attachment":[{"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/media?parent=73444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/categories?post=73444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.spring-reiter.de\/index.php\/wp-json\/wp\/v2\/tags?post=73444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}